{"id":80101,"date":"2024-02-10T00:00:00","date_gmt":"2024-02-10T00:00:00","guid":{"rendered":"https:\/\/expertato.com\/meeting-rooms\/directory\/holalkere-india\/"},"modified":"2024-02-10T00:00:00","modified_gmt":"2024-02-10T00:00:00","slug":"holalkere-india","status":"publish","type":"at_biz_dir","link":"https:\/\/expertato.com\/meeting-rooms\/directory\/holalkere-india\/","title":{"rendered":"Holalkere, India"},"content":{"rendered":"<p>Location: Holalkere, India (IN)<\/p>\n<p>Country: India<\/p>\n<p>Alternate Names: Holalkere,Kholalkere,holalakera,holalakere,holalkere,holalkire,hollalkeoleo,hou la ke li,huo la er kai lei,karimupongu,\u0425\u043e\u043b\u0430\u043b\u043a\u0435\u0440\u0435,\u06c1\u0648\u0644\u0627\u0644\u06a9\u06cc\u0631\u06cc,\u0939\u094b\u0932\u0932\u0915\u0947\u0930\u0947,\u0939\u094b\u0932\u093e\u0932\u0915\u0947\u0930\u0947,\u09b9\u09cb\u09b2\u09be\u09b2\u0995\u09c7\u09b0\u09c7,\u0ab9\u0acb\u0ab2\u0ab2\u0a95\u0ac7\u0ab0,\u0bb9\u0bcb\u0bb2\u0bbe\u0bb2\u0bcd\u0b95\u0bbf\u0bb0\u0bc7,\u0c39\u0c4b\u0c32\u0c3e\u0c32\u0c4d\u0c15\u0c47\u0c30\u0c47,\u0cb9\u0cca\u0cb3\u0cb2\u0ccd\u0c95\u0cc6\u0cb0\u0cc6,\u30ab\u30ea\u30e0\u30dd\u30f3\u30b0,\u4faf\u62c9\u514b\u88e1,\u4faf\u62c9\u514b\u91cc,\u970d\u62c9\u5c14\u51ef\u96f7,\ud640\ub784\ucee4\ub7ec <\/p>\n<p>Alternate Names Data Source: https:\/\/www.geonames.org<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","atbdp_listing_types":[6],"at_biz_dir-category":[46],"at_biz_dir-location":[],"at_biz_dir-tags":[],"class_list":["post-80101","at_biz_dir","type-at_biz_dir","status-publish","hentry","atbdp_listing_types-business-providers","at_biz_dir-category-rooms"],"_links":{"self":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir\/80101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir"}],"about":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/types\/at_biz_dir"}],"author":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/comments?post=80101"}],"wp:attachment":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/media?parent=80101"}],"wp:term":[{"taxonomy":"atbdp_listing_types","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/atbdp_listing_types?post=80101"},{"taxonomy":"at_biz_dir-category","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-category?post=80101"},{"taxonomy":"at_biz_dir-location","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-location?post=80101"},{"taxonomy":"at_biz_dir-tags","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-tags?post=80101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}