{"id":46994,"date":"2024-02-10T00:00:00","date_gmt":"2024-02-10T00:00:00","guid":{"rendered":"https:\/\/expertato.com\/meeting-rooms\/directory\/vic-fezensac-france\/"},"modified":"2024-02-10T00:00:00","modified_gmt":"2024-02-10T00:00:00","slug":"vic-fezensac-france","status":"publish","type":"at_biz_dir","link":"https:\/\/expertato.com\/meeting-rooms\/directory\/vic-fezensac-france\/","title":{"rendered":"Vic-Fezensac, France"},"content":{"rendered":"<p>Location: Vic-Fezensac, France (FR)<\/p>\n<p>Country: France<\/p>\n<p>Alternate Names: Vic de Fesensac,Vic en Fesensac,Vic-Fezensac,Vic-sur-l\u2019Osse,Vik-Fezansak,vuikku=fezansakku,wei ke fei cang sa ke,\u0412\u0438\u043a-\u0424\u0435\u0437\u0430\u043d\u0441\u0430\u043a,\u0412\u0456\u043a-\u0424\u0435\u0437\u0430\u043d\u0441\u0430\u043a,\u30f4\u30a3\u30c3\u30af\uff1d\u30d5\u30a7\u30b6\u30f3\u30b5\u30c3\u30af,\u7ef4\u514b\u8d39\u85cf\u8428\u514b <\/p>\n<p>Alternate Names Data Source: https:\/\/www.geonames.org<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","atbdp_listing_types":[6],"at_biz_dir-category":[46],"at_biz_dir-location":[],"at_biz_dir-tags":[],"class_list":["post-46994","at_biz_dir","type-at_biz_dir","status-publish","hentry","atbdp_listing_types-business-providers","at_biz_dir-category-rooms"],"_links":{"self":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir\/46994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir"}],"about":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/types\/at_biz_dir"}],"author":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/comments?post=46994"}],"wp:attachment":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/media?parent=46994"}],"wp:term":[{"taxonomy":"atbdp_listing_types","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/atbdp_listing_types?post=46994"},{"taxonomy":"at_biz_dir-category","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-category?post=46994"},{"taxonomy":"at_biz_dir-location","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-location?post=46994"},{"taxonomy":"at_biz_dir-tags","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-tags?post=46994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}