{"id":222651,"date":"2024-02-10T00:00:00","date_gmt":"2112-09-19T00:00:00","guid":{"rendered":"https:\/\/expertato.com\/meeting-rooms\/directory\/garden-city-south-dakota-usa\/"},"modified":"2024-02-10T00:00:00","modified_gmt":"2024-02-10T00:00:00","slug":"garden-city-south-dakota-usa","status":"publish","type":"at_biz_dir","link":"https:\/\/expertato.com\/meeting-rooms\/directory\/garden-city-south-dakota-usa\/","title":{"rendered":"Garden City, South Dakota (SD), United States of America (USA)"},"content":{"rendered":"<p>Location: Garden City, South Dakota (SD), United States of America (USA)<\/p>\n<p>Country: United States of America<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","atbdp_listing_types":[6],"at_biz_dir-category":[46],"at_biz_dir-location":[],"at_biz_dir-tags":[],"class_list":["post-222651","at_biz_dir","type-at_biz_dir","status-publish","hentry","atbdp_listing_types-business-providers","at_biz_dir-category-rooms"],"_links":{"self":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir\/222651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir"}],"about":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/types\/at_biz_dir"}],"author":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/comments?post=222651"}],"wp:attachment":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/media?parent=222651"}],"wp:term":[{"taxonomy":"atbdp_listing_types","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/atbdp_listing_types?post=222651"},{"taxonomy":"at_biz_dir-category","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-category?post=222651"},{"taxonomy":"at_biz_dir-location","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-location?post=222651"},{"taxonomy":"at_biz_dir-tags","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-tags?post=222651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}