{"id":198812,"date":"2024-02-10T00:00:00","date_gmt":"2047-06-13T00:00:00","guid":{"rendered":"https:\/\/expertato.com\/meeting-rooms\/directory\/hunterstown-pennsylvania-usa\/"},"modified":"2024-02-10T00:00:00","modified_gmt":"2024-02-10T00:00:00","slug":"hunterstown-pennsylvania-usa","status":"publish","type":"at_biz_dir","link":"https:\/\/expertato.com\/meeting-rooms\/directory\/hunterstown-pennsylvania-usa\/","title":{"rendered":"Hunterstown, Pennsylvania (PA), United States of America (USA)"},"content":{"rendered":"<p>Location: Hunterstown, Pennsylvania (PA), United States of America (USA)<\/p>\n<p>Country: United States of America<\/p>\n<p>Alternate Names: Ganterstaun,Hunterstown,Khanterstaun,Straban Center,Woodstock,hantrztawn,hantrztawn  pnsylwanya,\u0413\u0430\u043d\u0442\u0435\u0440\u0441\u0442\u0430\u0443\u043d,\u0425\u0430\u043d\u0442\u0435\u0440\u0441\u0442\u0430\u0443\u043d,\u0647\u0627\u0646\u062a\u0631\u0632\u062a\u0627\u0648\u0646,\u0647\u0627\u0646\u062a\u0631\u0632\u062a\u0627\u0648\u0646\u060c \u067e\u0646\u0633\u06cc\u0644\u0648\u0627\u0646\u06cc\u0627 <\/p>\n<p>Alternate Names Data Source: https:\/\/www.geonames.org<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","atbdp_listing_types":[6],"at_biz_dir-category":[46],"at_biz_dir-location":[],"at_biz_dir-tags":[],"class_list":["post-198812","at_biz_dir","type-at_biz_dir","status-publish","hentry","atbdp_listing_types-business-providers","at_biz_dir-category-rooms"],"_links":{"self":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir\/198812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir"}],"about":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/types\/at_biz_dir"}],"author":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/comments?post=198812"}],"wp:attachment":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/media?parent=198812"}],"wp:term":[{"taxonomy":"atbdp_listing_types","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/atbdp_listing_types?post=198812"},{"taxonomy":"at_biz_dir-category","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-category?post=198812"},{"taxonomy":"at_biz_dir-location","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-location?post=198812"},{"taxonomy":"at_biz_dir-tags","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-tags?post=198812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}