{"id":194558,"date":"2024-02-10T00:00:00","date_gmt":"2035-10-20T00:00:00","guid":{"rendered":"https:\/\/expertato.com\/meeting-rooms\/directory\/melbourne-beach-florida-usa\/"},"modified":"2024-02-10T00:00:00","modified_gmt":"2024-02-10T00:00:00","slug":"melbourne-beach-florida-usa","status":"publish","type":"at_biz_dir","link":"https:\/\/expertato.com\/meeting-rooms\/directory\/melbourne-beach-florida-usa\/","title":{"rendered":"Melbourne Beach, Florida (FL), United States of America (USA)"},"content":{"rendered":"<p>Location: Melbourne Beach, Florida (FL), United States of America (USA)<\/p>\n<p>Country: United States of America<\/p>\n<p>Alternate Names: Mel\u2019burn-Bich,Melborn-Bich,Melburn Bich,melbarna bica,mlbwrn bych  flwryda,mlbwrn bytsh,mo er ben hai tan,\u041c\u0435\u043b\u0431\u043e\u0440\u043d-\u0411\u0438\u0447,\u041c\u0435\u043b\u0431\u043e\u0440\u043d-\u0411\u0456\u0447,\u041c\u0435\u043b\u0431\u0443\u0440\u043d \u0411\u0438\u0447,\u041c\u0435\u043b\u044c\u0431\u0443\u0440\u043d-\u0411\u0438\u0447,\u0645\u0644\u0628\u0648\u0631\u0646 \u0628\u064a\u062a\u0634,\u0645\u0644\u0628\u0648\u0631\u0646 \u0628\u06cc\u0686\u060c \u0641\u0644\u0648\u0631\u06cc\u062f\u0627,\u092e\u0947\u0932\u094d\u092c\u0930\u094d\u0928 \u092c\u0940\u091a,\u58a8\u5c14\u672c\u6d77\u6ee9 <\/p>\n<p>Alternate Names Data Source: https:\/\/www.geonames.org<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","atbdp_listing_types":[6],"at_biz_dir-category":[46],"at_biz_dir-location":[],"at_biz_dir-tags":[],"class_list":["post-194558","at_biz_dir","type-at_biz_dir","status-publish","hentry","atbdp_listing_types-business-providers","at_biz_dir-category-rooms"],"_links":{"self":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir\/194558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir"}],"about":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/types\/at_biz_dir"}],"author":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/comments?post=194558"}],"wp:attachment":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/media?parent=194558"}],"wp:term":[{"taxonomy":"atbdp_listing_types","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/atbdp_listing_types?post=194558"},{"taxonomy":"at_biz_dir-category","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-category?post=194558"},{"taxonomy":"at_biz_dir-location","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-location?post=194558"},{"taxonomy":"at_biz_dir-tags","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-tags?post=194558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}