{"id":16910,"date":"2024-02-10T00:00:00","date_gmt":"2024-02-10T00:00:00","guid":{"rendered":"https:\/\/expertato.com\/meeting-rooms\/directory\/heers-belgium\/"},"modified":"2024-02-10T00:00:00","modified_gmt":"2024-02-10T00:00:00","slug":"heers-belgium","status":"publish","type":"at_biz_dir","link":"https:\/\/expertato.com\/meeting-rooms\/directory\/heers-belgium\/","title":{"rendered":"Heers, Belgium"},"content":{"rendered":"<p>Location: Heers, Belgium (BE)<\/p>\n<p>Country: Belgium<\/p>\n<p>Alternate Names: Heers,Hier,Hi\u00ebr <\/p>\n<p>Alternate Names Data Source: https:\/\/www.geonames.org<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","atbdp_listing_types":[6],"at_biz_dir-category":[46],"at_biz_dir-location":[],"at_biz_dir-tags":[],"class_list":["post-16910","at_biz_dir","type-at_biz_dir","status-publish","hentry","atbdp_listing_types-business-providers","at_biz_dir-category-rooms"],"_links":{"self":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir\/16910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir"}],"about":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/types\/at_biz_dir"}],"author":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/comments?post=16910"}],"wp:attachment":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/media?parent=16910"}],"wp:term":[{"taxonomy":"atbdp_listing_types","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/atbdp_listing_types?post=16910"},{"taxonomy":"at_biz_dir-category","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-category?post=16910"},{"taxonomy":"at_biz_dir-location","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-location?post=16910"},{"taxonomy":"at_biz_dir-tags","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-tags?post=16910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}