{"id":136901,"date":"2024-02-10T00:00:00","date_gmt":"2024-02-10T00:00:00","guid":{"rendered":"https:\/\/expertato.com\/meeting-rooms\/directory\/bhopalwala-pakistan\/"},"modified":"2024-02-10T00:00:00","modified_gmt":"2024-02-10T00:00:00","slug":"bhopalwala-pakistan","status":"publish","type":"at_biz_dir","link":"https:\/\/expertato.com\/meeting-rooms\/directory\/bhopalwala-pakistan\/","title":{"rendered":"Bhopalwala, Pakistan"},"content":{"rendered":"<p>Location: Bhopalwala, Pakistan (PK)<\/p>\n<p>Country: Pakistan<\/p>\n<p>Alternate Names: Bhopalwala <\/p>\n<p>Alternate Names Data Source: https:\/\/www.geonames.org<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","atbdp_listing_types":[6],"at_biz_dir-category":[46],"at_biz_dir-location":[],"at_biz_dir-tags":[],"class_list":["post-136901","at_biz_dir","type-at_biz_dir","status-publish","hentry","atbdp_listing_types-business-providers","at_biz_dir-category-rooms"],"_links":{"self":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir\/136901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir"}],"about":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/types\/at_biz_dir"}],"author":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/comments?post=136901"}],"wp:attachment":[{"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/media?parent=136901"}],"wp:term":[{"taxonomy":"atbdp_listing_types","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/atbdp_listing_types?post=136901"},{"taxonomy":"at_biz_dir-category","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-category?post=136901"},{"taxonomy":"at_biz_dir-location","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-location?post=136901"},{"taxonomy":"at_biz_dir-tags","embeddable":true,"href":"https:\/\/expertato.com\/meeting-rooms\/wp-json\/wp\/v2\/at_biz_dir-tags?post=136901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}